{"id":2002,"date":"2024-06-21T09:36:21","date_gmt":"2024-06-21T09:36:21","guid":{"rendered":"https:\/\/stage.hallwang2.smithberlin.com\/?post_type=disease&#038;p=2002"},"modified":"2025-03-11T13:02:29","modified_gmt":"2025-03-11T13:02:29","slug":"lungenkrebs","status":"publish","type":"disease","link":"https:\/\/www.hallwang-clinic.com\/de_DE\/disease\/lungenkrebs\/","title":{"rendered":"Lungenkrebs"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center\">Lungenkrebs (Bronchialkarzinom) z\u00e4hlt zu den h\u00e4ufigsten Krebsarten weltweit. Die Behandlung der Krankheit, insbesondere im fortgeschrittenen Stadium, erfordert individuell angepasste Therapiekonzepte. Die Hallwang Clinic setzt auf fortschrittliche Behandlungsoptionen wie Kombinationstherapien.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Was ist Lungenkrebs?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lungenkrebs, auch als Bronchialkarzinom bezeichnet, ist eine b\u00f6sartige Neubildung, die von den Zellen der Lunge oder Bronchien ausgeht. Charakteristisch f\u00fcr Tumorzellen sind unkontrolliertes Wachstum, vermehrte Zellteilung und die F\u00f6rderung der Blutgef\u00e4\u00dfbildung (Angiogenese). Tumore in der Lunge k\u00f6nnen auf zwei Arten entstanden sein: Entweder lokal, das hei\u00dft, der Tumor beginnt in der Lunge zu wachsen und kann auch in andere K\u00f6rperteile und Organe eindringen und sich dort ausbreiten (Metastasierung). Oder der Tumor ist eine Lungenmetastase, also eine Absiedlung eines Tumors aus einem anderen Organ.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt zwei histologische Haupttypen von Lungenkrebs: <strong>kleinzelliges Lungenkarzinom<\/strong> (Small-Cell Lung Cancer, SCLC) und <strong>nicht-kleinzelliges Lungenkarzinom<\/strong> (Non-Small-Cell Lung Cancer, NSCLC). Das NSCLC unterteilt sich wiederum in die Untertypen <strong>gro\u00dfzelliges Lungenkarzinom<\/strong> (Large-Cell Lung Cancer, LCLC), <strong>Adenokarzinom<\/strong> und <strong>Plattenepithelkarzinom<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Klassifikation der Tumore nach ihrem histologischen Erscheinungsbild ist wichtig f\u00fcr die Evaluierung des weiteren Verlaufs und die Behandlung der Krankheit. Dar\u00fcber hinaus spielen heutzutage immer mehr molekulargenetische Eigenschaften der Tumorentit\u00e4ten eine bedeutende Rolle. Mutationen in Genen wie EGFR, ALK, ROS1, cMET, HER2, RET und FGFR1 k\u00f6nnen gezielt behandelt werden. Moderne zielgerichtete Therapien und <a href=\"https:\/\/www.hallwang-clinic.com\/therapies\/immuntherapien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immuntherapien<\/a> verbessern die \u00dcberlebenschancen vieler Patienten erheblich. Eine umfassende Diagnostik, einschlie\u00dflich genetischer Analysen, erm\u00f6glicht eine pr\u00e4zisere Therapieauswahl und kann den Erfolg der Behandlung ma\u00dfgeblich beeinflussen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Diagnose Lungenkrebs<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Anzeichen und Symptome von Lungenkrebs sind vielf\u00e4ltig und k\u00f6nnen Schmerzen in der Brust, Husten, Bluthusten, Atemnot, Gewichtsverlust, Schw\u00e4che oder Fieber umfassen. In fr\u00fchen Stadien bleibt ein Bronchialkarzinom h\u00e4ufig unentdeckt, da die Symptome unspezifisch oder nicht vorhanden sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Erstdiagnose erfolgt normalerweise durch bildgebende Diagnostik. Ein sogenannter PET-CT-Scan (Positronen-Emissions-Tomographie kombiniert mit Computertomographie) gibt Aufschluss dar\u00fcber, ob und wo sich Tumormassen im K\u00f6rper befinden. Er zeigt auf, ob der Tumor sich bereits auf andere Gewebe ausgebreitet hat. Wenn bildgebende Verfahren eine verd\u00e4chtige Masse zeigen, erfolgt eine Gewebeentnahme (Biopsie), um die Eigenschaften des Tumors zu bestimmen. Eine histopathologische Analyse kann dann den genauen (Zell-)Typ des Tumors identifizieren. Es gibt viele verschiedene Arten von Tumoren und jeder von ihnen weist einzigartige genetische Merkmale auf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den meisten universit\u00e4ren Zentren geh\u00f6rt es mittlerweile zum Standard, molekulargenetische Screening-Analysen durchzuf\u00fchren. Was viele Patientinnen und Patienten nicht wissen: Sollte im Rahmen der Biopsie kein solches Screening erfolgt sein, ist eine nachtr\u00e4gliche Analyse des Gewebematerials m\u00f6glich. Das Gewebe wird nach der ersten Untersuchung der Biopsie (zur Bestimmung des Tumortyps) in der histopathologischen Abteilung des Krankenhauses aufbewahrt und l\u00e4sst sich f\u00fcr weiterf\u00fchrende (genetische) Gewebeanalysen und Sequenzierungen verwenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tumore weisen oft mehrere genetische Modifikationen auf, die den Krebszellen einen selektiven Wachstumsvorteil verschaffen. Mittels fortschrittlich entwickelten Hochdurchsatztechnologien ist eine Identifizierung dieser mutierten Gene m\u00f6glich, die zu einer wirksam zielgerichteten Therapie f\u00fchren k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein <a href=\"https:\/\/www.hallwang-clinic.com\/uber-uns\/ihre-analysen\/\" target=\"_blank\" rel=\"noreferrer noopener\">gr\u00fcndliches Screening am Tumorgewebe<\/a> ist daher entscheidend, um alle potenziellen Behandlungsoptionen auszusch\u00f6pfen. Moderne zielgerichtete Therapien oder Immuntherapien basieren auf individuellen Tumormerkmalen und haben die Behandlungsm\u00f6glichkeiten von Lungenkrebs erheblich erweitert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr eine optimale Therapie ist es wichtig, ein spezialisiertes Labor f\u00fcr die genetische Analyse zu w\u00e4hlen und mit einem Onkologen zusammenzuarbeiten, der die Ergebnisse in einen ma\u00dfgeschneiderten Behandlungsplan integriert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lungenkrebs-Behandlung: Welche ist die beste Therapie?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Einige Lungentumore k\u00f6nnen operativ entfernt werden, sofern sie als operabel gelten. In anderen F\u00e4llen empfehlen Onkologen vor oder nach dem chirurgischen Eingriff eine Chemotherapie und\/oder eine Strahlentherapie. Da diese Therapieformen allerdings mit erheblichen zytotoxischen Nebenwirkungen einhergehen, hat sich beim Bronchialkarzinom eine weitere Therapieoption etabliert: der Einsatz von <a href=\"https:\/\/www.hallwang-clinic.com\/therapies\/immuntherapien\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immuntherapien<\/a>.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Immuntherapie bei Lungenkrebs<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Immuntherapie gilt als bahnbrechender Fortschritt in der Krebsbehandlung, da sie das k\u00f6rpereigene Immunsystem gezielt aktiviert, um Krebszellen zu erkennen und zu zerst\u00f6ren. Dabei kommen zwei kombinierbare Ans\u00e4tze zum Einsatz:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>1. Aktive Immunisierung: <\/strong>Dieser Ansatz trainiert das Immunsystem des Patienten, Tumorzellen zu erkennen und anzugreifen, was zu Zellzerst\u00f6rung oder verlangsamtem Tumorwachstum f\u00fchrt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2. Passive Immunisierung<\/strong>: Hierbei werden Antik\u00f6rper oder Antik\u00f6rperfragmente per Infusion beziehungsweise Injektion verabreicht, die gezielt Krebszellen angreifen und zerst\u00f6ren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Bandbreite der immuntherapeutischen Ans\u00e4tze ist gro\u00df. Sie reicht von Antik\u00f6rper-Wirkstoff-Konjugaten (Antibody-Drug-Conjugates, ADC) \u00fcber Checkpoint-blockierende Antik\u00f6rper (Anti-CTLA-4 oder Anti-PD-1\/PD-L1) bis hin zu monoklonalen, polyklonalen und trifunktionalen Antik\u00f6rpern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bronchialkarzinom: Weitere Therapien<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Zu den weiteren Behandlungsoptionen von Lungenkrebs stehen neben der Immuntherapie bereits l\u00e4nger genetisch gezielte Therapien gegen EGFR-Mutation (epidermaler Wachstumsfaktor-Rezeptor) sowie molekular-genetisch gezielte Therapien gegen cMET, ALK, ROS1, RET, HER2 und FGFR1 zur Verf\u00fcgung.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zunehmend setzen sich bei der Behandlung von Lungenkrebs Kombinationstherapien durch, welche ein hohes Ma\u00df an Expertise und langj\u00e4hriger Erfahrung auf dem Gebiet der Pr\u00e4zisionsmedizin erfordern. Als hochspezialisierte onkologische Privatklinik stehen wir Ihnen als Partner zur Seite.<\/p>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<div class=\"wp-block-group has-text-color has-background has-link-color wp-elements-1\" style=\"color:#000000;background-color:#ffffff\">\n<h2 class=\"wp-block-heading\">Umbrellakonzept<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Umbrellakonzept ber\u00fccksichtigt alle Aspekte der Krankengeschichte des Patienten, weitere Diagnosen, das allgemeine Wohlbefinden, sowie die verf\u00fcgbaren diagnostischen Konstellationen und laufenden Behandlungen. Ein Umbrellakonzept beruht nicht auf der einen oder der anderen Therapieoption, sondern zieht eine pr\u00e4zisionsbasierte Kombination von Therapien in Betracht, die f\u00fcr jeden Einzelfall bewertet werden.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Behandlung von Lungenkrebs in der Hallwang Clinic<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Hallwang Clinic hat eines der modernsten genomischen und immuntherapeutischen Profile weltweit entwickelt. Dank unseres erstklassigen Expertennetzwerks, enger Forschungskooperationen und uneingeschr\u00e4nkten Zugangs zu den innovativsten Therapien verf\u00fcgen wir \u00fcber einen entscheidenden Vorteil in der Bereitstellung personalisierter Krebsbehandlungen. Unser <a href=\"https:\/\/www.hallwang-clinic.com\/uber-uns\/onkologen\/\" target=\"_blank\" rel=\"noreferrer noopener\">hochspezialisiertes Onkologieteam<\/a> setzt auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hochmoderne Pr\u00e4zisionsmedizin<\/li>\n\n\n\n<li>Umfassende genetische Analyse zur gezielten Therapie<\/li>\n\n\n\n<li>Kombinationstherapien f\u00fcr verbesserte Behandlungsergebnisse<\/li>\n\n\n\n<li>Ganzheitliche und integrative onkologische Betreuung.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">So gelingt es uns, herausragende Ergebnisse zu erzielen und die \u00dcberlebensraten zu verbessern \u2013 selbst bei Patienten mit <a href=\"https:\/\/www.hallwang-clinic.com\/therapies\/krebstherapien-im-stadium-4\/\" target=\"_blank\" rel=\"noreferrer noopener\">Krebs im Stadium 4<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der Suche nach der besten Lungenkrebs-Behandlung entscheiden sich Patienten aus aller Welt f\u00fcr die Hallwang Clinic. Neben den fortschrittlichen Therapiekonzepten, der exzellenten medizinischen Versorgung und der internationalen Ausrichtung tr\u00e4gt auch die vertrauensvolle, einf\u00fchlsame Atmosph\u00e4re dazu bei, die bestm\u00f6gliche Behandlung zu f\u00f6rdern.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lassen Sie sich beraten<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unser onkologisches Team ber\u00e4t Sie gerne telefonisch, um einen tieferen Einblick in Ihren speziellen Fall zu erhalten. Dies erm\u00f6glicht es uns auch, Ihnen einen vorl\u00e4ufigen Behandlungsplan und einen Kostenvoranschlag zu erstellen. Unsere Onkologen informieren Sie detailliert \u00fcber Medikamente, Therapien und Behandlungen, einschlie\u00dflich der zugrundeliegenden Mechanismen und Nebenwirkungen.<\/p>\n\n\n\n<p class=\"has-inn-font-family wp-block-paragraph\">Nach einer k\u00f6rperlichen Untersuchung und einem ausf\u00fchrlichen Gespr\u00e4ch mit Ihnen vor Ort wird der definitive Behandlungsplan besprochen. Bitte haben Sie Verst\u00e4ndnis daf\u00fcr, dass komplexe medizinische Prozesse wie oben erw\u00e4hnt nur durch eine eingehende Beratung vor Ort erkl\u00e4rt werden k\u00f6nnen.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\">\n<div class=\"wp-block-group has-text-color has-background has-link-color wp-elements-2\" style=\"color:#000000;background-color:#ffffff\">\n<h3 class=\"wp-block-heading has-text-align-center\">Kontaktieren Sie uns. <br>Wir helfen Ihnen gern!<\/h3>\n\n\n\n<div class=\"wp-block-buttons\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/www.hallwang-clinic.com\/?page_id=1586\">JETZT KONTAKT AUFNEHMEN<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"featured_media":2689,"template":"","class_list":["post-2002","disease","type-disease","status-publish","has-post-thumbnail","hentry","de_DE","teaser-view"],"_links":{"self":[{"href":"https:\/\/www.hallwang-clinic.com\/wp-json\/wp\/v2\/disease\/2002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hallwang-clinic.com\/wp-json\/wp\/v2\/disease"}],"about":[{"href":"https:\/\/www.hallwang-clinic.com\/wp-json\/wp\/v2\/types\/disease"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hallwang-clinic.com\/wp-json\/wp\/v2\/media\/2689"}],"wp:attachment":[{"href":"https:\/\/www.hallwang-clinic.com\/wp-json\/wp\/v2\/media?parent=2002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}